{"id":1116057,"date":"2026-04-01T08:46:13","date_gmt":"2026-04-01T06:46:13","guid":{"rendered":"https:\/\/hubsch-interior.com\/product\/product\/"},"modified":"2026-05-13T05:11:21","modified_gmt":"2026-05-13T03:11:21","slug":"como-lampenschirm","status":"publish","type":"product","link":"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/","title":{"rendered":"Como Lampenschirm"},"content":{"rendered":"<p>Ersatzteile f\u00fcr den Lampenschirm der Como-Leuchte. Die Leuchte besteht aus drei Teilen, die sich durch einfaches Auf- und Abschrauben m\u00fchelos austauschen lassen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ersatzteile f\u00fcr den Lampenschirm der Como-Leuchte. Die Leuchte besteht aus drei Teilen, die sich durch einfaches Auf- und Abschrauben m\u00fchelos austauschen lassen.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[3809,5081,5047,4172],"product_tag":[],"class_list":{"0":"post-1116057","1":"product","2":"type-product","3":"status-publish","5":"product_cat-beleuchtung","6":"product_cat-gerade-auf-lager-de","7":"product_cat-neuheiten-de","8":"product_cat-zubehoer-fuer-beleuchtung-de","9":"product_shipping_class-pk","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como Lampenschirm - H\u00fcbsch<\/title>\n<meta name=\"description\" content=\"Ersatzteile f\u00fcr den Lampenschirm der Como-Leuchte. Die Leuchte besteht aus drei Teilen, die sich durch einfaches Auf- und Abschrauben m\u00fchelos austauschen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product\/1116057\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como Lampenschirm - H\u00fcbsch\" \/>\n<meta property=\"og:description\" content=\"Ersatzteile f\u00fcr den Lampenschirm der Como-Leuchte. Die Leuchte besteht aus drei Teilen, die sich durch einfaches Auf- und Abschrauben m\u00fchelos austauschen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00fcbsch\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T03:11:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/\",\"url\":\"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/\",\"name\":\"Como Lampenschirm - H\u00fcbsch\",\"isPartOf\":{\"@id\":\"https:\/\/hubsch-interior.com\/de\/#website\"},\"datePublished\":\"2026-04-01T06:46:13+00:00\",\"dateModified\":\"2026-05-13T03:11:21+00:00\",\"description\":\"Ersatzteile f\u00fcr den Lampenschirm der Como-Leuchte. Die Leuchte besteht aus drei Teilen, die sich durch einfaches Auf- und Abschrauben m\u00fchelos austauschen\",\"breadcrumb\":{\"@id\":\"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/hubsch-interior.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\/\/hubsch-interior.com\/de\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como Lampenschirm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/#website\",\"url\":\"https:\/\/hubsch-interior.com\/de\/\",\"name\":\"H\u00fcbsch\",\"description\":\"Danish Home Interior and Design\",\"publisher\":{\"@id\":\"https:\/\/hubsch-interior.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hubsch-interior.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/#organization\",\"name\":\"H\u00fcbsch\",\"url\":\"https:\/\/hubsch-interior.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hubsch-interior.com\/wp-content\/uploads\/2022\/12\/Hubsch_logo_black_one_line.svg\",\"contentUrl\":\"https:\/\/hubsch-interior.com\/wp-content\/uploads\/2022\/12\/Hubsch_logo_black_one_line.svg\",\"caption\":\"H\u00fcbsch\"},\"image\":{\"@id\":\"https:\/\/hubsch-interior.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como Lampenschirm - H\u00fcbsch","description":"Ersatzteile f\u00fcr den Lampenschirm der Como-Leuchte. Die Leuchte besteht aus drei Teilen, die sich durch einfaches Auf- und Abschrauben m\u00fchelos austauschen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product\/1116057","og_locale":"de_DE","og_type":"article","og_title":"Como Lampenschirm - H\u00fcbsch","og_description":"Ersatzteile f\u00fcr den Lampenschirm der Como-Leuchte. Die Leuchte besteht aus drei Teilen, die sich durch einfaches Auf- und Abschrauben m\u00fchelos austauschen","og_url":"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/","og_site_name":"H\u00fcbsch","article_modified_time":"2026-05-13T03:11:21+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/","url":"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/","name":"Como Lampenschirm - H\u00fcbsch","isPartOf":{"@id":"https:\/\/hubsch-interior.com\/de\/#website"},"datePublished":"2026-04-01T06:46:13+00:00","dateModified":"2026-05-13T03:11:21+00:00","description":"Ersatzteile f\u00fcr den Lampenschirm der Como-Leuchte. Die Leuchte besteht aus drei Teilen, die sich durch einfaches Auf- und Abschrauben m\u00fchelos austauschen","breadcrumb":{"@id":"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hubsch-interior.com\/de\/produkt\/como-lampenschirm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hubsch-interior.com\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/hubsch-interior.com\/de\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Como Lampenschirm"}]},{"@type":"WebSite","@id":"https:\/\/hubsch-interior.com\/de\/#website","url":"https:\/\/hubsch-interior.com\/de\/","name":"H\u00fcbsch","description":"Danish Home Interior and Design","publisher":{"@id":"https:\/\/hubsch-interior.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hubsch-interior.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hubsch-interior.com\/de\/#organization","name":"H\u00fcbsch","url":"https:\/\/hubsch-interior.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hubsch-interior.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hubsch-interior.com\/wp-content\/uploads\/2022\/12\/Hubsch_logo_black_one_line.svg","contentUrl":"https:\/\/hubsch-interior.com\/wp-content\/uploads\/2022\/12\/Hubsch_logo_black_one_line.svg","caption":"H\u00fcbsch"},"image":{"@id":"https:\/\/hubsch-interior.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product\/1116057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/media?parent=1116057"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product_brand?post=1116057"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product_cat?post=1116057"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product_tag?post=1116057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}