{"id":4156,"count":15,"description":"","link":"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/","name":"B&uuml;roartikel","slug":"bueroartikel-de","taxonomy":"product_cat","parent":4155,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>B&uuml;roartikel - H\u00fcbsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product_cat\/4156\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B&uuml;roartikel - H\u00fcbsch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00fcbsch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/\",\"url\":\"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/\",\"name\":\"B&uuml;roartikel - H\u00fcbsch\",\"isPartOf\":{\"@id\":\"https:\/\/hubsch-interior.com\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/hubsch-interior.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wohnaccessoires\",\"item\":\"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"B&uuml;ro\",\"item\":\"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"B&uuml;roartikel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/#website\",\"url\":\"https:\/\/hubsch-interior.com\/de\/\",\"name\":\"H\u00fcbsch\",\"description\":\"Danish Home Interior and Design\",\"publisher\":{\"@id\":\"https:\/\/hubsch-interior.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hubsch-interior.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/#organization\",\"name\":\"H\u00fcbsch\",\"url\":\"https:\/\/hubsch-interior.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/hubsch-interior.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hubsch-interior.com\/wp-content\/uploads\/2022\/12\/Hubsch_logo_black_one_line.svg\",\"contentUrl\":\"https:\/\/hubsch-interior.com\/wp-content\/uploads\/2022\/12\/Hubsch_logo_black_one_line.svg\",\"caption\":\"H\u00fcbsch\"},\"image\":{\"@id\":\"https:\/\/hubsch-interior.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B&uuml;roartikel - H\u00fcbsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product_cat\/4156","og_locale":"de_DE","og_type":"article","og_title":"B&uuml;roartikel - H\u00fcbsch","og_url":"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/","og_site_name":"H\u00fcbsch","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/","url":"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/","name":"B&uuml;roartikel - H\u00fcbsch","isPartOf":{"@id":"https:\/\/hubsch-interior.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/bueroartikel-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hubsch-interior.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wohnaccessoires","item":"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/"},{"@type":"ListItem","position":3,"name":"B&uuml;ro","item":"https:\/\/hubsch-interior.com\/de\/produkt-kategorie\/wohnaccessoires\/buero-de\/"},{"@type":"ListItem","position":4,"name":"B&uuml;roartikel"}]},{"@type":"WebSite","@id":"https:\/\/hubsch-interior.com\/de\/#website","url":"https:\/\/hubsch-interior.com\/de\/","name":"H\u00fcbsch","description":"Danish Home Interior and Design","publisher":{"@id":"https:\/\/hubsch-interior.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hubsch-interior.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hubsch-interior.com\/de\/#organization","name":"H\u00fcbsch","url":"https:\/\/hubsch-interior.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hubsch-interior.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hubsch-interior.com\/wp-content\/uploads\/2022\/12\/Hubsch_logo_black_one_line.svg","contentUrl":"https:\/\/hubsch-interior.com\/wp-content\/uploads\/2022\/12\/Hubsch_logo_black_one_line.svg","caption":"H\u00fcbsch"},"image":{"@id":"https:\/\/hubsch-interior.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product_cat\/4156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product_cat\/4155"}],"wp:post_type":[{"href":"https:\/\/hubsch-interior.com\/de\/wp-json\/wp\/v2\/product?product_cat=4156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}